{"id":689,"count":68,"description":"","link":"https:\/\/hadiaslebanesecuisine.com\/blog\/category\/lebanese-recipes\/appetizers-lebanese-recipes\/","name":"Appetizers","slug":"appetizers-lebanese-recipes","taxonomy":"category","parent":464,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Appetizers Archives - hadias lebanese cuisine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hadiaslebanesecuisine.com\/blog\/category\/lebanese-recipes\/appetizers-lebanese-recipes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Appetizers Archives - hadias lebanese cuisine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hadiaslebanesecuisine.com\/blog\/category\/lebanese-recipes\/appetizers-lebanese-recipes\/\" \/>\n<meta property=\"og:site_name\" content=\"hadias lebanese cuisine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/category\\\/lebanese-recipes\\\/appetizers-lebanese-recipes\\\/\",\"url\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/category\\\/lebanese-recipes\\\/appetizers-lebanese-recipes\\\/\",\"name\":\"Appetizers Archives - hadias lebanese cuisine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/category\\\/lebanese-recipes\\\/appetizers-lebanese-recipes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/category\\\/lebanese-recipes\\\/appetizers-lebanese-recipes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lebanese Recipes\",\"item\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/category\\\/lebanese-recipes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Appetizers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/\",\"name\":\"hadias lebanese cuisine\",\"description\":\"Hadia, Lebanese Style Recipes\",\"publisher\":{\"@id\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/#organization\",\"name\":\"hadias lebanese cuisine\",\"url\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-rectangularlogo256-131.png\",\"contentUrl\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-rectangularlogo256-131.png\",\"width\":256,\"height\":128,\"caption\":\"hadias lebanese cuisine\"},\"image\":{\"@id\":\"https:\\\/\\\/hadiaslebanesecuisine.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Appetizers Archives - hadias lebanese cuisine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hadiaslebanesecuisine.com\/blog\/category\/lebanese-recipes\/appetizers-lebanese-recipes\/","og_locale":"en_US","og_type":"article","og_title":"Appetizers Archives - hadias lebanese cuisine","og_url":"https:\/\/hadiaslebanesecuisine.com\/blog\/category\/lebanese-recipes\/appetizers-lebanese-recipes\/","og_site_name":"hadias lebanese cuisine","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hadiaslebanesecuisine.com\/blog\/category\/lebanese-recipes\/appetizers-lebanese-recipes\/","url":"https:\/\/hadiaslebanesecuisine.com\/blog\/category\/lebanese-recipes\/appetizers-lebanese-recipes\/","name":"Appetizers Archives - hadias lebanese cuisine","isPartOf":{"@id":"https:\/\/hadiaslebanesecuisine.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/hadiaslebanesecuisine.com\/blog\/category\/lebanese-recipes\/appetizers-lebanese-recipes\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/hadiaslebanesecuisine.com\/blog\/category\/lebanese-recipes\/appetizers-lebanese-recipes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hadiaslebanesecuisine.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Lebanese Recipes","item":"https:\/\/hadiaslebanesecuisine.com\/blog\/category\/lebanese-recipes\/"},{"@type":"ListItem","position":3,"name":"Appetizers"}]},{"@type":"WebSite","@id":"https:\/\/hadiaslebanesecuisine.com\/blog\/#website","url":"https:\/\/hadiaslebanesecuisine.com\/blog\/","name":"hadias lebanese cuisine","description":"Hadia, Lebanese Style Recipes","publisher":{"@id":"https:\/\/hadiaslebanesecuisine.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hadiaslebanesecuisine.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hadiaslebanesecuisine.com\/blog\/#organization","name":"hadias lebanese cuisine","url":"https:\/\/hadiaslebanesecuisine.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hadiaslebanesecuisine.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/hadiaslebanesecuisine.com\/blog\/wp-content\/uploads\/2024\/11\/cropped-rectangularlogo256-131.png","contentUrl":"https:\/\/hadiaslebanesecuisine.com\/blog\/wp-content\/uploads\/2024\/11\/cropped-rectangularlogo256-131.png","width":256,"height":128,"caption":"hadias lebanese cuisine"},"image":{"@id":"https:\/\/hadiaslebanesecuisine.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hadiaslebanesecuisine.com\/blog\/wp-json\/wp\/v2\/categories\/689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hadiaslebanesecuisine.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hadiaslebanesecuisine.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/hadiaslebanesecuisine.com\/blog\/wp-json\/wp\/v2\/categories\/464"}],"wp:post_type":[{"href":"https:\/\/hadiaslebanesecuisine.com\/blog\/wp-json\/wp\/v2\/posts?categories=689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}